{"id":4925,"date":"2018-05-16T19:25:19","date_gmt":"2018-05-16T18:25:19","guid":{"rendered":"http:\/\/ecole.ecj23.org\/?p=4925"},"modified":"2018-05-16T19:25:19","modified_gmt":"2018-05-16T18:25:19","slug":"escrime-en-9c","status":"publish","type":"post","link":"https:\/\/ecole.ecj23.org\/index.php\/2018\/05\/16\/escrime-en-9c\/","title":{"rendered":"Escrime en 9C"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Pendant le 1<sup>er<\/sup> trimestre, chaque jeudi matin, nous retrouvions Thierry pour notre s\u00e9ance d\u2019escrime.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Nous souhaitons vous le faire d\u00e9couvrir\u00a0:<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>L\u2019escrime est un\u00a0<a style=\"color: #3366ff;\" href=\"http:\/\/www.infobebes.com\/Enfant\/Loisirs\/Quelles-activites-pour-mon-enfant\/Sport\">sport<\/a>\u00a0de combat dans lequel le but est de toucher sans se faire toucher. Avant de commencer, nous devons nous \u00e9quipons. Nous enfilons notre veste, puis nous prenons notre masque. Thierry nous donne ensuite notre fleuret. Mais attention, la pointe doit rester au sol tant que nous n\u2019utilisons pas l\u2019arme.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Dans un premier temps, Thierry nous a appris \u00e0 bien tenir notre fleuret. C\u2019est important car cela nous permet de diriger sa pointe avec pr\u00e9cision\u00a0 pour toucher. Puis, il nous montre la position de garde qui permet d\u2019\u00eatre pr\u00eat pour attaquer ou pour se d\u00e9fendre. Pour parfaire notre technique, Thierry nous fait travailler nos d\u00e9placements avec des jeux. Nous apprenons \u00e0 marcher, \u00e0 rompre (reculer) et \u00e0 nous fendre. Nous apprenons aussi quelques techniques comme la parade et la riposte. Mais ce que nous pr\u00e9f\u00e9rons, ce sont les tournois\u00a0! On salue toujours notre adversaire avant de commencer puis on se met en garde. <em>A la fin du tournoi, nous devons nous serrer la main.<\/em><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong><em>Nous aimons beaucoup ce sport car nous devons \u00eatre pr\u00e9cis et rapides\u00a0! <\/em><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong><em>Les mousquetaires de la 9C<\/em><\/strong><\/span><\/p>\n<div id=\"grid-gallery-242-83269\" data-gg-id=\"242\" data-title=\"Escrime 9C\" data-grid-type=\"0\" data-offset=\"5.3\" data-area-position=\"center\" data-icons=\"\" data-preloader=\"true\" data-width=\"215\" data-height=\"215\" data-padding=\"0\" data-quicksand=\"disabled\" data-quicksand-duration=\"none\" data-popup-theme=\"theme_6\" data-popup-type=\"pretty-photo\" data-popup-image-text=\"data-description\" data-popup-widthsize=\"auto\" data-popup-heightsize=\"auto\" data-popup-i18n-words=\"{&quot;close&quot;:&quot;fermer&quot;,&quot;next&quot;:&quot;suivant&quot;,&quot;previous&quot;:&quot;pr\\u00e9c\\u00e9dent&quot;,&quot;start_slideshow&quot;:&quot;d\\u00e9marrer le diaporama&quot;,&quot;stop_slideshow&quot;:&quot;arr\\u00e9ter le diaporama&quot;,&quot;image&quot;:&quot;image&quot;,&quot;of&quot;:&quot;de&quot;,&quot;prev&quot;:&quot;pr\\u00e9c.&quot;,&quot;cExpand&quot;:&quot;Agrandir&quot;,&quot;cPrevious&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;cNext&quot;:&quot;Suivant&quot;,&quot;cExpandStr&quot;:&quot;Agrandir l&#039;image&quot;,&quot;cRotate&quot;:&quot;Pivoter&quot;,&quot;cDetails&quot;:&quot;Details&quot;}\" data-popup-slideshow=\"false\" data-popup-slideshow-speed=\"2500\" data-popup-hoverstop=\"false\" data-popup-slideshow-auto=\"false\" data-popup-background=\"\" data-popup-transparency=\"30\" data-popup-disable-history=\"\" data-popup-disable-changed-url=\"\" data-popup-border-type=\"\" data-popup-border-color=\"\" data-popup-border-width=\"\" data-popup-border-enable=\"\" data-fullscreen=\"false\" data-hide-tooltip=\"false\" data-caption-font-family=\"Default\" data-caption-text-size=\"140\" data-is-mobile=\"0\" data-caption-mobile=\"false\" data-hide-long-tltp-title=\"0\" data-caption-disabled-on-mobile=\"false\" data-horizontal-scroll=\"{&quot;enabled&quot;:&quot;true&quot;,&quot;color&quot;:&quot;#f7005a&quot;,&quot;transparency&quot;:&quot;60&quot;}\" data-popup-placement-type=\"0\" data-social-sharing=\"{&quot;enabled&quot;:&quot;&quot;,&quot;gallerySharing&quot;:{&quot;enabled&quot;:null,&quot;position&quot;:null},&quot;imageSharing&quot;:{&quot;enabled&quot;:null,&quot;wrapperClass&quot;:&quot; vertical &quot;},&quot;popupSharing&quot;:{&quot;enabled&quot;:null,&quot;wrapperClass&quot;:&quot; vertical &quot;}}\" class=\"grid-gallery grid-gallery-fixed \" style=\" width:100%; height:auto; margin-left:auto; margin-right:auto;position:relative;\"> <div class=\"gallery-loading\"> <div class=\"blocks\"> <div class=\"block\"><\/div> <div class=\"block\"><\/div> <div class=\"block\"><\/div> <div class=\"block\"><\/div> <\/div> <\/div> <div class=\"gallery-sharing-top\" style=\"display:none;\"> <\/div> <div id=\"photos-242\" class=\"grid-gallery-photos\"><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"0\" style=\"display:none;border-radius:00;; margin:5.3px; width:2150;\" ><div class=\"crop\" style=\" width:2150; height:2150; overflow:hidden;\"><img decoding=\"async\" src=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2018\/05\/20171124_152116-215x215.jpg\" class=\"ggImg\" alt=\"\" title=\"\" data-description=\"\" data-caption=\"\" data-title=\"\" style=\" width:215px; height:215px;\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:140; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\"\"><\/div><\/FIGCAPTION><\/FIGURE><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"1\" style=\"display:none;border-radius:00;; margin:5.3px; width:2150;\" ><div class=\"crop\" style=\" width:2150; height:2150; overflow:hidden;\"><img decoding=\"async\" src=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2018\/05\/20171117_144557-e1526494943131-215x215.jpg\" class=\"ggImg\" alt=\"\" title=\"\" data-description=\"\" data-caption=\"\" data-title=\"\" style=\" width:215px; height:215px;\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:140; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\"\"><\/div><\/FIGCAPTION><\/FIGURE><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"2\" style=\"display:none;border-radius:00;; margin:5.3px; width:2150;\" ><div class=\"crop\" style=\" width:2150; height:2150; overflow:hidden;\"><img decoding=\"async\" src=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2018\/05\/20171117_142019-e1526494920432-215x215.jpg\" class=\"ggImg\" alt=\"\" title=\"\" data-description=\"\" data-caption=\"\" data-title=\"\" style=\" width:215px; height:215px;\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:140; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\"\"><\/div><\/FIGCAPTION><\/FIGURE><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"3\" style=\"display:none;border-radius:00;; margin:5.3px; width:2150;\" ><div class=\"crop\" style=\" width:2150; height:2150; overflow:hidden;\"><img decoding=\"async\" src=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2018\/05\/20171005_144849-e1526494897909-215x215.jpg\" class=\"ggImg\" alt=\"\" title=\"\" data-description=\"\" data-caption=\"\" data-title=\"\" style=\" width:215px; height:215px;\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:140; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\"\"><\/div><\/FIGCAPTION><\/FIGURE><FIGURE class=\"grid-gallery-caption\" data-grid-gallery-type=\"quarter-slide-up\" data-index=\"4\" style=\"display:none;border-radius:00;; margin:5.3px; width:2150;\" ><div class=\"crop\" style=\" width:2150; height:2150; overflow:hidden;\"><img decoding=\"async\" src=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2018\/05\/20171005_143033-e1526494882609-215x215.jpg\" class=\"ggImg\" alt=\"\" title=\"\" data-description=\"\" data-caption=\"\" data-title=\"\" style=\" width:215px; height:215px;\" \/><\/div><FIGCAPTION class=\"\" data-alpha=\"5\" style=\"color:#ffffff; background-color:#6f0000; font-size:140; text-align:left; font-family:Default;\" ><div class=\"grid-gallery-figcaption-wrap\" style=\"\"><\/div><\/FIGCAPTION><\/FIGURE> <div class=\"grid-gallery-clearfix\"><\/div> <\/div> <div class=\"gallery-sharing-bottom\" style=\"display:none;\"> <\/div> <div class=\"gallery-sharing-image\" style=\"display:none;\"> <\/div> <div class=\"gallery-sharing-popup\" style=\"display:none;\"> <\/div> <div class=\"grid-gallery-clearfix\"><\/div> <\/div> <!-- Gallery by Supsystic plugin1.16.2 --><a title=\"Gallery Plugin\" style=\"display:none;\" href=\"https:\/\/supsystic.com\/plugins\/photo-gallery\/?utm_medium=love_link\" target=\"_blank\">Gallery Plugin<\/a>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pendant le 1er trimestre, chaque jeudi matin, nous retrouvions Thierry pour notre s\u00e9ance d\u2019escrime. Nous souhaitons vous le faire d\u00e9couvrir\u00a0: L\u2019escrime est un\u00a0sport\u00a0de combat dans lequel le but est de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3,11],"tags":[],"class_list":["post-4925","post","type-post","status-publish","format-standard","hentry","category-espace-classes","category-neuviemes"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts\/4925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/comments?post=4925"}],"version-history":[{"count":2,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts\/4925\/revisions"}],"predecessor-version":[{"id":4932,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts\/4925\/revisions\/4932"}],"wp:attachment":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/media?parent=4925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/categories?post=4925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/tags?post=4925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}