{"id":6369,"date":"2019-03-01T08:46:01","date_gmt":"2019-03-01T07:46:01","guid":{"rendered":"http:\/\/ecole.ecj23.org\/?p=6369"},"modified":"2019-03-01T08:46:19","modified_gmt":"2019-03-01T07:46:19","slug":"les-grands-travaux-a-jean-xxiii","status":"publish","type":"post","link":"https:\/\/ecole.ecj23.org\/index.php\/2019\/03\/01\/les-grands-travaux-a-jean-xxiii\/","title":{"rendered":"Les grands travaux \u00e0 Jean XXIII"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un article est paru dans le journal l&rsquo;Alsace du 27-02-2019 sur notre campagne de travaux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cet article parle notamment de l&rsquo;installation de l\u2019ascenseur et des nouvelles salles pr\u00e9vu au sous-sol de l&rsquo;\u00e9cole primaire.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"853\" src=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2019\/03\/article_alsace_ecj23_travaux.jpg\" alt=\"\" class=\"wp-image-6370\" srcset=\"https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2019\/03\/article_alsace_ecj23_travaux.jpg 960w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2019\/03\/article_alsace_ecj23_travaux-300x267.jpg 300w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2019\/03\/article_alsace_ecj23_travaux-768x682.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un article est paru dans le journal l&rsquo;Alsace du 27-02-2019 sur notre campagne de travaux. Cet article parle notamment de l&rsquo;installation de l\u2019ascenseur et des nouvelles salles pr\u00e9vu au sous-sol [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-6369","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts\/6369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/comments?post=6369"}],"version-history":[{"count":1,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts\/6369\/revisions"}],"predecessor-version":[{"id":6371,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts\/6369\/revisions\/6371"}],"wp:attachment":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/media?parent=6369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/categories?post=6369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/tags?post=6369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}