{"id":8700,"date":"2022-06-10T21:36:24","date_gmt":"2022-06-10T19:36:24","guid":{"rendered":"http:\/\/ecole.ecj23.org\/?p=8700"},"modified":"2023-03-21T08:46:10","modified_gmt":"2023-03-21T07:46:10","slug":"sortie-a-lecomusee-pour-les-cm2e","status":"publish","type":"post","link":"https:\/\/ecole.ecj23.org\/index.php\/2022\/06\/10\/sortie-a-lecomusee-pour-les-cm2e\/","title":{"rendered":"Sortie \u00e0 l&rsquo;\u00e9comus\u00e9e pour les CM2E"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\">Le 26 avril dernier, nous avons eu le plaisir de d\u00e9couvrir ou red\u00e9couvrir un village alsacien du d\u00e9but du XXe si\u00e8cle , reconstruit au c\u0153ur de la nature alsacienne \u00e0 Ungersheim.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A travers un jeu de piste et un atelier poterie, nous avons pu remonter le temps et imaginer la vie de nos anc\u00eatres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un concours de dessin nous a permis de prendre le temps d\u2019observer notre environnement et nous avons pris conscience de l\u2019importance de respecter la richesse de notre patrimoine et de ce que la nature nous offre.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_091800.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" data-id=\"8701\" src=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_091800-1024x766.jpg\" alt=\"\" class=\"wp-image-8701\" srcset=\"https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_091800-1024x766.jpg 1024w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_091800-300x224.jpg 300w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_091800-768x574.jpg 768w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_091800.jpg 1249w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_121945.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" data-id=\"8702\" src=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_121945-1024x766.jpg\" alt=\"\" class=\"wp-image-8702\" srcset=\"https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_121945-1024x766.jpg 1024w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_121945-300x224.jpg 300w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_121945-768x574.jpg 768w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_121945.jpg 1249w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_133722-rotated.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"766\" height=\"1024\" data-id=\"8703\" src=\"http:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_133722-766x1024.jpg\" alt=\"\" class=\"wp-image-8703\" srcset=\"https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_133722-766x1024.jpg 766w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_133722-224x300.jpg 224w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_133722-768x1027.jpg 768w, https:\/\/ecole.ecj23.org\/wp-content\/uploads\/2022\/06\/IMG_20220426_133722-rotated.jpg 1014w\" sizes=\"auto, (max-width: 766px) 100vw, 766px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Le 26 avril dernier, nous avons eu le plaisir de d\u00e9couvrir ou red\u00e9couvrir un village alsacien du d\u00e9but du XXe si\u00e8cle , reconstruit au c\u0153ur de la nature alsacienne \u00e0 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[101,1],"tags":[],"class_list":["post-8700","post","type-post","status-publish","format-standard","hentry","category-2021-2022","category-non-classe"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts\/8700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/comments?post=8700"}],"version-history":[{"count":1,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts\/8700\/revisions"}],"predecessor-version":[{"id":8704,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/posts\/8700\/revisions\/8704"}],"wp:attachment":[{"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/media?parent=8700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/categories?post=8700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecole.ecj23.org\/index.php\/wp-json\/wp\/v2\/tags?post=8700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}